{"id":124983,"date":"2024-05-16T17:49:51","date_gmt":"2024-05-16T17:49:51","guid":{"rendered":"https:\/\/immopascual.com\/propiedad\/chalet-pareado-en-cala-romantica\/"},"modified":"2024-05-16T17:49:51","modified_gmt":"2024-05-16T17:49:51","slug":"chalet-pareado-en-cala-romantica","status":"publish","type":"property","link":"https:\/\/immopascual.com\/es\/propiedad\/chalet-pareado-en-cala-romantica\/","title":{"rendered":"CHALET PAREADO  EN CALA ROMANTICA"},"content":{"rendered":"<p>En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila   os ofrecemos la posibilidad de comprar su casa con jard\u00edn.<br \/>\nEs un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las casas no tienen vistas al mar sino al bosque<br \/>\nEn la primera fase le ofrecemos 30 viviendas pareadas con terrazas, jard\u00edn plaza de parking y si lo quiere piscina privada (suplemento de unos 15.000 euros).<\/p>\n<p>Las viviendas de la primera fase tendr\u00e1n su propia comunidad al igual que las siguientes fases, adem\u00e1s el complejo estar\u00e1 provisto de un spa, una piscina exterior e interior y el gimnasio<br \/>\nel gimnasio totalmente equipado y dedicado a su salud y bienestar.<br \/>\ncuenta con un cine privado, un bar gastron\u00f3mico y un espacio social donde pasar tiempo<br \/>\ncon amigos, familiares y vecinos.<br \/>\nCala Rom\u00e1ntica se sit\u00faa a 20 minutos de Manacor y 10 minutos del hospital Llevant de porto cristo, en la zona tenemos restaurantes, actividades n\u00e1uticas, l\u00edneas de .bus.<br \/>\nLa obra que se va a reiniciar pronto, es su oportunidad de reservar su vivienda.<br \/>\nLa vivienda   ofrece en planta baja un sal\u00f3n comedor de 53 m2 dando a un porche de 40 m2 una cocina de 7.50 m2 una habitaci\u00f3n en suite, un aseo de invitados y una coladuria. La vivienda se entregar\u00e1 con la cocina y electrodom\u00e9sticos de nivel Bosch o siemens, pero ten\u00e9is tambi\u00e9n la posibilidad de solicitar muchas<br \/>\nEl chalet  tiene 3 habitaciones , 3 ba\u00f1os y un aseo en una superficie construida de 234 m2 y \u00fatil de 150 m2 , el solar es de 720 m2 que os permite construir una piscina privada .<\/p>\n<p>La primera fase se entregar\u00e1 junto a la urbanizaci\u00f3n y zonas comunes correspondientes, en 3T 2025<br \/>\nEl pago se realizar\u00e1 asi:<br \/>\n5000 euros + iva  a la reserva de la vivienda<br \/>\n20%+IVA menos la reserva inicial a la firma del contrato de compraventa (enero 2024)<br \/>\na los seis meses siguientes 10 % m\u00e1s iva<br \/>\nlo dem\u00e1s a la escritura ante notario (prevista en tercer trimestre 2025)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":124984,"parent":0,"menu_order":0,"template":"","property_type":[3],"property_status":[50],"property_feature":[],"property_label":[],"property_state":[9],"property_city":[362],"property_area":[158],"class_list":["post-124983","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-casa-chalet","property_status-venta","property_state-mallorca","property_city-porto-cristo","property_area-porto-cristo"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Immopascual\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/immopascual.com\/es\/propiedad\/chalet-pareado-en-cala-romantica\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Immopascual - Inmobiliaria Pascual Associats\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CHALET PAREADO EN CALA ROMANTICA - Immopascual\" \/>\n\t\t<meta property=\"og:description\" content=\"En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/immopascual.com\/es\/propiedad\/chalet-pareado-en-cala-romantica\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-16T17:49:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-16T17:49:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CHALET PAREADO EN CALA ROMANTICA - Immopascual\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CHALET PAREADO EN CALA ROMANTICA - Immopascual","description":"En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las","canonical_url":"https:\/\/immopascual.com\/es\/propiedad\/chalet-pareado-en-cala-romantica\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"Immopascual - Inmobiliaria Pascual Associats","og:type":"article","og:title":"CHALET PAREADO EN CALA ROMANTICA - Immopascual","og:description":"En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las","og:url":"https:\/\/immopascual.com\/es\/propiedad\/chalet-pareado-en-cala-romantica\/","article:published_time":"2024-05-16T17:49:51+00:00","article:modified_time":"2024-05-16T17:49:51+00:00","twitter:card":"summary","twitter:title":"CHALET PAREADO EN CALA ROMANTICA - Immopascual","twitter:description":"En cala Rom\u00e1ntica a solo cinco minutos de la playa de s\u2019Estany den Mas, tambi\u00e9n cerca de cala Mandia y cala anguila os ofrecemos la posibilidad de comprar su casa con jard\u00edn. Es un complejo que tendr\u00e1 en total unas 160 viviendas, cada vivienda con su plaza de parquin, su terraza y su jard\u00edn, las"},"aioseo_meta_data":{"post_id":"124983","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-05-18 05:28:13","updated":"2025-06-15 11:49:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/immopascual.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/immopascual.com\/es\/propiedad\/\" title=\"Propiedades\">Propiedades<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/immopascual.com\/es\/property-type\/casa-chalet\/\" title=\"Casa\/Chalet\">Casa\/Chalet<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCHALET PAREADO  EN CALA ROMANTICA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/immopascual.com\/es\/"},{"label":"Propiedades","link":"https:\/\/immopascual.com\/es\/propiedad\/"},{"label":"Casa\/Chalet","link":"https:\/\/immopascual.com\/es\/property-type\/casa-chalet\/"},{"label":"CHALET PAREADO  EN CALA ROMANTICA","link":"https:\/\/immopascual.com\/es\/propiedad\/chalet-pareado-en-cala-romantica\/"}],"property_meta":{"lastUpdate":["2026-03-26T09:59:01.550"],"fave_property_id":["C1414"],"fave_property_price":["795375.00"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["4"],"fave_property_size":["234"],"fave_property_land":["720"],"fave_property_year":["2008"],"_thumbnail_id":["124984"],"fave_property_images":["124984","124989","124994","124999","125004","125009","125014","125019","125024","125029","125034","125039","125044","125049","125054","125059","125072","125077","125082","125087"],"_wpml_word_count":["{\"total\":374,\"to_translate\":{\"ca\":374,\"en\":374,\"fr\":374,\"de\":374}}"],"houzez_total_property_views":["1639"],"houzez_views_by_date":["a:61:{s:10:\"05-13-2026\";i:1;s:10:\"05-14-2026\";i:3;s:10:\"05-15-2026\";i:2;s:10:\"05-16-2026\";i:2;s:10:\"05-17-2026\";i:2;s:10:\"05-18-2026\";i:1;s:10:\"05-19-2026\";i:2;s:10:\"05-20-2026\";i:3;s:10:\"05-21-2026\";i:3;s:10:\"05-22-2026\";i:2;s:10:\"05-24-2026\";i:2;s:10:\"05-25-2026\";i:3;s:10:\"05-26-2026\";i:2;s:10:\"05-28-2026\";i:2;s:10:\"05-29-2026\";i:5;s:10:\"05-30-2026\";i:2;s:10:\"05-31-2026\";i:2;s:10:\"06-01-2026\";i:3;s:10:\"06-02-2026\";i:2;s:10:\"06-03-2026\";i:1;s:10:\"06-04-2026\";i:2;s:10:\"06-05-2026\";i:2;s:10:\"06-06-2026\";i:1;s:10:\"06-07-2026\";i:3;s:10:\"06-08-2026\";i:3;s:10:\"06-10-2026\";i:3;s:10:\"06-11-2026\";i:4;s:10:\"06-12-2026\";i:2;s:10:\"06-13-2026\";i:2;s:10:\"06-14-2026\";i:1;s:10:\"06-15-2026\";i:3;s:10:\"06-16-2026\";i:3;s:10:\"06-17-2026\";i:1;s:10:\"06-18-2026\";i:4;s:10:\"06-19-2026\";i:2;s:10:\"06-20-2026\";i:1;s:10:\"06-21-2026\";i:2;s:10:\"06-22-2026\";i:4;s:10:\"06-23-2026\";i:1;s:10:\"06-24-2026\";i:2;s:10:\"06-25-2026\";i:3;s:10:\"06-26-2026\";i:3;s:10:\"06-27-2026\";i:4;s:10:\"06-28-2026\";i:7;s:10:\"06-29-2026\";i:4;s:10:\"06-30-2026\";i:6;s:10:\"07-01-2026\";i:4;s:10:\"07-02-2026\";i:2;s:10:\"07-03-2026\";i:2;s:10:\"07-04-2026\";i:3;s:10:\"07-05-2026\";i:2;s:10:\"07-06-2026\";i:4;s:10:\"07-07-2026\";i:1;s:10:\"07-08-2026\";i:3;s:10:\"07-09-2026\";i:2;s:10:\"07-10-2026\";i:2;s:10:\"07-11-2026\";i:4;s:10:\"07-12-2026\";i:1;s:10:\"07-13-2026\";i:2;s:10:\"07-14-2026\";i:1;s:10:\"07-15-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-15 01:22:09"],"fave_featured":["0"]},"_links":{"self":[{"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/properties\/124983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/properties\/124983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/media\/124984"}],"wp:attachment":[{"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/media?parent=124983"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_type?post=124983"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_status?post=124983"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_feature?post=124983"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_label?post=124983"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_state?post=124983"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_city?post=124983"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/immopascual.com\/es\/wp-json\/wp\/v2\/property_area?post=124983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}